{"id":2896,"date":"2022-09-29T19:41:06","date_gmt":"2022-09-29T18:41:06","guid":{"rendered":"https:\/\/bakerplus.net\/?page_id=2896"},"modified":"2023-03-17T17:17:03","modified_gmt":"2023-03-17T16:17:03","slug":"corrupted-films","status":"publish","type":"page","link":"https:\/\/bakerplus.net\/de\/corrupted-films\/","title":{"rendered":"Corrupted Films"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2896\" class=\"elementor elementor-2896\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-107a9e2 elementor-section-full_width elementor-section-height-min-height elementor-section-items-top elementor-section-height-default\" data-id=\"107a9e2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:2382,&quot;url&quot;:&quot;https:\\\/\\\/bakerplus.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/rsz_screen_shot_2022-03-12_at_72153_pm.png&quot;}],&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-770d9c8\" data-id=\"770d9c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbf91ed elementor-widget elementor-widget-image\" data-id=\"cbf91ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"341\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2022\/09\/corruptedfilms-LOGOTEXT-VERTICAL.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-2906\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8e60118 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"8e60118\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dc2d5cc\" data-id=\"dc2d5cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7805805 elementor-widget elementor-widget-heading\" data-id=\"7805805\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Films by 0n3Appl3<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-391a37d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"391a37d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d29485\" data-id=\"0d29485\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6827dea elementor-widget elementor-widget-progression-video-carousel-list\" data-id=\"6827dea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"progression-video-carousel-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n\n\t\n\t<div class=\"progression-studios-elementor-video-carousel-container\">\n        \n        <div class=\"progression-studios-carousel-overflow \" style=\"margin-left:-10px; margin-right:-10px; padding-left:10px; padding-right:10px;\">\n\t\t\t<div id=\"progression-studios-carousel-elementor-6827dea\" class=\"progression-studios-season-video-list aztec-carousel\">\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-1820\" class=\"post-1820 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-movies video-genres-action video-genres-minecraft video-category-minecraft video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/droidema\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/droidema.jpg\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" srcset=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/droidema.jpg 1280w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/droidema-300x169.jpg 300w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/droidema-1024x576.jpg 1024w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/droidema-768x432.jpg 768w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/droidema-565x318.jpg 565w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-2144\" class=\"post-2144 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-series video-genres-bplus-picks video-genres-drama video-genres-minecraft video-genres-thriller video-category-corrupted-universe video-category-featured-series video-category-minecraft video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/diversion\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder.jpg\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" srcset=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder.jpg 1280w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder-300x169.jpg 300w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder-1024x576.jpg 1024w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder-768x432.jpg 768w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder-565x318.jpg 565w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-1877\" class=\"post-1877 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-movies video-genres-fantasy video-genres-medieval video-genres-minecraft video-category-award-winning video-category-minecraft video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/crimes-of-alorion\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2022\/02\/rsz_crimes-of-alorion.png\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-1836\" class=\"post-1836 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-movies video-genres-action video-genres-bplus-picks video-genres-drama video-genres-minecraft video-category-award-winning video-category-corrupted-universe video-category-minecraft video-category-slider-movies video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/onyx-rebooted\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2022\/02\/onyx-rebooted.png\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-2184\" class=\"post-2184 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-movies video-genres-action video-genres-minecraft video-category-award-winning video-category-minecraft video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/outside\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2022\/03\/rsz_outside_ma_thmb.png\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-1866\" class=\"post-1866 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-movies video-genres-crime video-genres-minecraft video-genres-thriller video-category-minecraft video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/one-lane-bridge\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/07\/one-lane-bridge.jpg\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" srcset=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/07\/one-lane-bridge.jpg 1280w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/07\/one-lane-bridge-300x169.jpg 300w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/07\/one-lane-bridge-1024x576.jpg 1024w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/07\/one-lane-bridge-768x432.jpg 768w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/07\/one-lane-bridge-565x318.jpg 565w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-2381\" class=\"post-2381 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-documentary video-type-series video-genres-comedy video-genres-minecraft video-category-featured-series video-category-minecraft video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/workspaces\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2022\/04\/FNoS8pRagAIMelp.jpg\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-1818\" class=\"post-1818 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-movies video-genres-action video-genres-minecraft video-category-minecraft video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/outset\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/outset.jpg\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" srcset=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/outset.jpg 1280w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/outset-300x169.jpg 300w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/outset-1024x576.jpg 1024w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/outset-768x432.jpg 768w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/outset-565x318.jpg 565w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-3133\" class=\"post-3133 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-movies video-genres-action video-genres-minecraft video-category-corrupted-universe video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/heat-one\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2022\/11\/heatone-thumbnail.png\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-1810\" class=\"post-1810 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-movies video-genres-action video-genres-drama video-genres-minecraft video-category-corrupted-universe video-category-minecraft video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/red-tears-unravelled\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/red-tears-unravelled.jpg\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" srcset=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/red-tears-unravelled.jpg 1280w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/red-tears-unravelled-300x169.jpg 300w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/red-tears-unravelled-1024x576.jpg 1024w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/red-tears-unravelled-768x432.jpg 768w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/red-tears-unravelled-565x318.jpg 565w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-3457\" class=\"post-3457 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-movies video-genres-action video-genres-medieval video-genres-minecraft video-category-corrupted-universe video-category-minecraft video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/lookout\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2023\/04\/maxresdefault-14.jpg\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t\t\t\t<\/div><!-- close #progression-video-index-masonry-6827dea  -->\n        <\/div><!-- close .progression-studios-carousel-overflow -->\n\t\t<div class=\"clearfix-pro\"><\/div>\n\t\t\n\t\n\t<\/div><!-- close .progression-studios-elementor-video-carousel-container -->\n\t\n    \n    \n    \n\t<script type=\"text\/javascript\">\n\tjQuery(document).ready(function($) {\n\t\t'use strict';\n\t\t\n\t\t$('#progression-studios-carousel-elementor-6827dea').owlCarousel({\n\t\t    margin:10,\n    \t\titemElement: \"li\",\n    \t\tstageElement: \"ul\",\n\t\t    items:6,\n\t\t\tnav: true,\n\t\t\tslideBy:1,\n            itemClass: \"aztec-carousel-item\",\n            \t\t    loop:false,\n                        rewind: false,\n            onTranslated: AztecDisplayPrevNav6827dea,\n            responsive : {\n\t\t\t    \/\/ breakpoint from 0 up\n\t\t\t    0 : {\n\t\t\t        items:4,\n\t\t\t    },\n\t\t\t    \/\/ breakpoint from 768 up\n\t\t\t    768 : {\n\t\t\t        items:5,\n\t\t\t    },\n\t\t\t    \/\/ breakpoint from 1025 up\n\t\t\t    1025 : {\n\t\t\t        items:6,\n\t\t\t    }\n\t\t\t}\n\t\t});\n        \n        function AztecDisplayPrevNav6827dea(){ $(\"#progression-studios-carousel-elementor-6827dea\").addClass(\"aztec-carousel-left-arrow-on\"); }\n\t\t\n\t});\n\t<\/script>\n    \n\t\n\n\t\t\n\n    \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f55f426 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f55f426\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d7335df\" data-id=\"d7335df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48da8b8 elementor-widget elementor-widget-heading\" data-id=\"48da8b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Featured Work<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e472f08 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e472f08\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-852f091\" data-id=\"852f091\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-920df9e elementor-widget elementor-widget-progression-video-carousel-list\" data-id=\"920df9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"progression-video-carousel-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n\n\t\n\t<div class=\"progression-studios-elementor-video-carousel-container\">\n        \n        <div class=\"progression-studios-carousel-overflow \" style=\"margin-left:-10px; margin-right:-10px; padding-left:10px; padding-right:10px;\">\n\t\t\t<div id=\"progression-studios-carousel-elementor-920df9e\" class=\"progression-studios-season-video-list aztec-carousel\">\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-1836\" class=\"post-1836 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-movies video-genres-action video-genres-bplus-picks video-genres-drama video-genres-minecraft video-category-award-winning video-category-corrupted-universe video-category-minecraft video-category-slider-movies video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/onyx-rebooted\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2022\/02\/onyx-rebooted.png\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-2144\" class=\"post-2144 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-series video-genres-bplus-picks video-genres-drama video-genres-minecraft video-genres-thriller video-category-corrupted-universe video-category-featured-series video-category-minecraft video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/diversion\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder.jpg\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" srcset=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder.jpg 1280w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder-300x169.jpg 300w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder-1024x576.jpg 1024w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder-768x432.jpg 768w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder-565x318.jpg 565w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t\t\t\t<\/div><!-- close #progression-video-index-masonry-920df9e  -->\n        <\/div><!-- close .progression-studios-carousel-overflow -->\n\t\t<div class=\"clearfix-pro\"><\/div>\n\t\t\n\t\n\t<\/div><!-- close .progression-studios-elementor-video-carousel-container -->\n\t\n    \n    \n    \n\t<script type=\"text\/javascript\">\n\tjQuery(document).ready(function($) {\n\t\t'use strict';\n\t\t\n\t\t$('#progression-studios-carousel-elementor-920df9e').owlCarousel({\n\t\t    margin:10,\n    \t\titemElement: \"li\",\n    \t\tstageElement: \"ul\",\n\t\t    items:6,\n\t\t\tnav: true,\n\t\t\tslideBy:1,\n            itemClass: \"aztec-carousel-item\",\n                        loop: false,\/* Fix for infinite loop without enoguh posts. Doens't quite work on tablet\/mobile though *\/\n                        rewind: false,\n            onTranslated: AztecDisplayPrevNav920df9e,\n            responsive : {\n\t\t\t    \/\/ breakpoint from 0 up\n\t\t\t    0 : {\n\t\t\t        items:4,\n\t\t\t    },\n\t\t\t    \/\/ breakpoint from 768 up\n\t\t\t    768 : {\n\t\t\t        items:5,\n\t\t\t    },\n\t\t\t    \/\/ breakpoint from 1025 up\n\t\t\t    1025 : {\n\t\t\t        items:6,\n\t\t\t    }\n\t\t\t}\n\t\t});\n        \n        function AztecDisplayPrevNav920df9e(){ $(\"#progression-studios-carousel-elementor-920df9e\").addClass(\"aztec-carousel-left-arrow-on\"); }\n\t\t\n\t});\n\t<\/script>\n    \n\t\n\n\t\t\n\n    \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e7d214 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1e7d214\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43987ce\" data-id=\"43987ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7bfff1 elementor-widget elementor-widget-heading\" data-id=\"d7bfff1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Corrupted Universe<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-465e795 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"465e795\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ffe6ba0\" data-id=\"ffe6ba0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0136837 elementor-widget elementor-widget-progression-video-carousel-list\" data-id=\"0136837\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"progression-video-carousel-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n\n\t\n\t<div class=\"progression-studios-elementor-video-carousel-container\">\n        \n        <div class=\"progression-studios-carousel-overflow \" style=\"margin-left:-10px; margin-right:-10px; padding-left:10px; padding-right:10px;\">\n\t\t\t<div id=\"progression-studios-carousel-elementor-0136837\" class=\"progression-studios-season-video-list aztec-carousel\">\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-2144\" class=\"post-2144 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-series video-genres-bplus-picks video-genres-drama video-genres-minecraft video-genres-thriller video-category-corrupted-universe video-category-featured-series video-category-minecraft video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/diversion\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder.jpg\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" srcset=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder.jpg 1280w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder-300x169.jpg 300w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder-1024x576.jpg 1024w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder-768x432.jpg 768w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/04\/diversion-e1-disorder-565x318.jpg 565w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-1810\" class=\"post-1810 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-movies video-genres-action video-genres-drama video-genres-minecraft video-category-corrupted-universe video-category-minecraft video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/red-tears-unravelled\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/red-tears-unravelled.jpg\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" srcset=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/red-tears-unravelled.jpg 1280w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/red-tears-unravelled-300x169.jpg 300w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/red-tears-unravelled-1024x576.jpg 1024w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/red-tears-unravelled-768x432.jpg 768w, https:\/\/bakerplus.net\/wp-content\/uploads\/2021\/03\/red-tears-unravelled-565x318.jpg 565w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-1836\" class=\"post-1836 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-movies video-genres-action video-genres-bplus-picks video-genres-drama video-genres-minecraft video-category-award-winning video-category-corrupted-universe video-category-minecraft video-category-slider-movies video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/onyx-rebooted\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2022\/02\/onyx-rebooted.png\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-3133\" class=\"post-3133 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-movies video-genres-action video-genres-minecraft video-category-corrupted-universe video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/heat-one\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2022\/11\/heatone-thumbnail.png\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t   \n\t\t\t\t    \n    <div id=\"post-3457\" class=\"post-3457 video_skrn type-video_skrn status-publish has-post-thumbnail hentry video-type-movies video-genres-action video-genres-medieval video-genres-minecraft video-category-corrupted-universe video-category-minecraft video-director-corrupted-films\">\t\n    \t<div class=\"progression-studios-video-index\">\n            \n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/bakerplus.net\/de\/title\/lookout\/\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\n\t\t\n    \t\t                <div class=\"progression-video-feaured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/bakerplus.net\/wp-content\/uploads\/2023\/04\/maxresdefault-14.jpg\" class=\"attachment-video-portrait-progression-studios size-video-portrait-progression-studios wp-post-image\" alt=\"\" \/><\/div><!-- close .progression-studios-feaured-image -->\n            \n    \t\t<div class=\"progression-video-index-content\">\n\t\t\t\t\n\n       \n                <!--- close the theme_mod_option -->\n                \n                \n               \n                \n                \t\t\t\n                                \n                                \n                \n                \n                                \n                \n                                \n                \n                                \n                                \n   \n    \t\t\t<div class=\"clearfix-pro\"><\/div>\t\n    \t\t<\/div><!-- close .progression-video-index-content -->\n\t\n    \t    <\/a><!-- Link -->\n        \n    \t<\/div><!-- close .progression-studios-video-index -->\n    <\/div><!-- #post-## -->\n    \n    \n    \n\n\n\t\t\t\t\t\t\t<\/div><!-- close #progression-video-index-masonry-0136837  -->\n        <\/div><!-- close .progression-studios-carousel-overflow -->\n\t\t<div class=\"clearfix-pro\"><\/div>\n\t\t\n\t\n\t<\/div><!-- close .progression-studios-elementor-video-carousel-container -->\n\t\n    \n    \n    \n\t<script type=\"text\/javascript\">\n\tjQuery(document).ready(function($) {\n\t\t'use strict';\n\t\t\n\t\t$('#progression-studios-carousel-elementor-0136837').owlCarousel({\n\t\t    margin:10,\n    \t\titemElement: \"li\",\n    \t\tstageElement: \"ul\",\n\t\t    items:6,\n\t\t\tnav: true,\n\t\t\tslideBy:1,\n            itemClass: \"aztec-carousel-item\",\n                        loop: false,\/* Fix for infinite loop without enoguh posts. Doens't quite work on tablet\/mobile though *\/\n                        rewind: false,\n            onTranslated: AztecDisplayPrevNav0136837,\n            responsive : {\n\t\t\t    \/\/ breakpoint from 0 up\n\t\t\t    0 : {\n\t\t\t        items:4,\n\t\t\t    },\n\t\t\t    \/\/ breakpoint from 768 up\n\t\t\t    768 : {\n\t\t\t        items:5,\n\t\t\t    },\n\t\t\t    \/\/ breakpoint from 1025 up\n\t\t\t    1025 : {\n\t\t\t        items:6,\n\t\t\t    }\n\t\t\t}\n\t\t});\n        \n        function AztecDisplayPrevNav0136837(){ $(\"#progression-studios-carousel-elementor-0136837\").addClass(\"aztec-carousel-left-arrow-on\"); }\n\t\t\n\t});\n\t<\/script>\n    \n\t\n\n\t\t\n\n    \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Films by 0n3Appl3 Featured Work Corrupted Universe<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-2896","page","type-page","status-publish","hentry"],"aioseo_notices":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:23:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"pp_notify_user","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/bakerplus.net\/de\/wp-json\/wp\/v2\/pages\/2896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bakerplus.net\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bakerplus.net\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bakerplus.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bakerplus.net\/de\/wp-json\/wp\/v2\/comments?post=2896"}],"version-history":[{"count":6,"href":"https:\/\/bakerplus.net\/de\/wp-json\/wp\/v2\/pages\/2896\/revisions"}],"predecessor-version":[{"id":3432,"href":"https:\/\/bakerplus.net\/de\/wp-json\/wp\/v2\/pages\/2896\/revisions\/3432"}],"wp:attachment":[{"href":"https:\/\/bakerplus.net\/de\/wp-json\/wp\/v2\/media?parent=2896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}